{"id":4089,"date":"2022-11-13T06:34:03","date_gmt":"2022-11-13T06:34:03","guid":{"rendered":"https:\/\/www.dr-mfo.com\/?page_id=4089"},"modified":"2026-02-22T06:57:38","modified_gmt":"2026-02-22T06:57:38","slug":"politica-de-privacidad-y-cookies","status":"publish","type":"page","link":"https:\/\/www.dr-mfo.com\/es\/privacy-cookie-policy\/","title":{"rendered":"Pol\u00edtica de privacidad y cookies"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4089\" class=\"elementor elementor-4089\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-173831b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"173831b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8716729\" data-id=\"8716729\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29de44a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"29de44a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-507694a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"507694a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3af7a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3af7a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-206a2c6\" data-id=\"206a2c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5015d18 elementor-widget elementor-widget-heading\" data-id=\"5015d18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Pol\u00edtica de privacidad y cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f73e6b elementor-widget elementor-widget-text-editor\" data-id=\"2f73e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Recopilamos informaci\u00f3n sobre usted cuando se registra en nuestro sitio o completa un formulario.<br>Al realizar un pedido o registrarse en nuestro sitio, seg\u00fan corresponda, se le puede solicitar que ingrese su nombre, direcci\u00f3n de correo electr\u00f3nico, n\u00famero de tel\u00e9fono u otros detalles para ayudarlo con su experiencia.<\/p>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>\u00bfPara qu\u00e9 utilizamos su informaci\u00f3n?<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Cualquiera de la informaci\u00f3n que recopilamos de usted puede usarse de una de las siguientes maneras:<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li>Para personalizar su experiencia (su informaci\u00f3n nos ayuda a responder mejor a sus necesidades individuales)<\/li>\n<li>Para mejorar nuestro sitio web (nos esforzamos continuamente por mejorar la oferta de nuestro sitio web en funci\u00f3n de la informaci\u00f3n y los comentarios que recibimos de usted)<\/li>\n<li>Para mejorar el servicio al cliente (su informaci\u00f3n nos ayuda a responder de manera m\u00e1s efectiva a sus solicitudes de servicio al cliente y necesidades de soporte)<\/li>\n<li>Para procesar transacciones<br>Su informaci\u00f3n, ya sea p\u00fablica o privada, no se vender\u00e1, intercambiar\u00e1, transferir\u00e1 ni entregar\u00e1 a ninguna otra empresa por ning\u00fan motivo, sin su consentimiento, que no sea con el prop\u00f3sito expreso de entregar el producto comprado o el servicio solicitado por el cliente.<\/li>\n<li>Para enviar correos electr\u00f3nicos peri\u00f3dicos<br>La direcci\u00f3n de correo electr\u00f3nico que proporcione para el procesamiento de pedidos puede usarse para enviarle informaci\u00f3n y actualizaciones relacionadas con su pedido, adem\u00e1s de recibir noticias ocasionales de la compa\u00f1\u00eda, actualizaciones, informaci\u00f3n relacionada con productos o servicios, etc.<\/li>\n<li>Para administrar un concurso, promoci\u00f3n, encuesta u otra funci\u00f3n del sitio<\/li>\n<\/ul>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>\u00bfC\u00f3mo protegemos tu informaci\u00f3n?<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Implementamos una variedad de medidas de seguridad para mantener la seguridad de su informaci\u00f3n personal. No utilizamos escaneo de vulnerabilidades y\/o escaneo seg\u00fan est\u00e1ndares PCI.<\/p>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>\u00bfUsamos cookies?<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">No utilizamos cookies con fines de seguimiento.<br>Puede elegir que su computadora le avise cada vez que se env\u00eda una cookie, o puede optar por desactivar todas las cookies. Usted hace esto a trav\u00e9s de la configuraci\u00f3n de su navegador. Si desactiva las cookies, se desactivar\u00e1n algunas funciones que hacen que su experiencia en el sitio sea m\u00e1s eficiente y algunos de nuestros servicios no funcionar\u00e1n correctamente. Sin embargo, a\u00fan puede realizar pedidos.<\/p>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>\u00bfRevelamos informaci\u00f3n a terceros?<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">No vendemos, intercambiamos ni transferimos a terceros su informaci\u00f3n de identificaci\u00f3n personal.<\/p>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>Enlaces de terceros<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">No incluimos ni ofrecemos productos o servicios de terceros en nuestro sitio web.<\/p>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>Google<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">No hemos habilitado Google AdSense en nuestro sitio.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">De acuerdo con CalOPPA, estamos de acuerdo con lo siguiente:<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li>Los usuarios pueden visitar nuestro sitio de forma an\u00f3nima.<\/li>\n<li>Una vez que se crea esta pol\u00edtica de privacidad, agregaremos un enlace en nuestra p\u00e1gina de inicio o, como m\u00ednimo, en la primera p\u00e1gina significativa despu\u00e9s de ingresar a nuestro sitio web.<\/li>\n<li>El enlace de nuestra Pol\u00edtica de privacidad incluye la palabra &quot;Privacidad&quot; y se puede encontrar f\u00e1cilmente en la p\u00e1gina especificada anteriormente.<\/li>\n<\/ul>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>Cambios a nuestra Pol\u00edtica de Privacidad<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Si decidimos cambiar nuestra pol\u00edtica de privacidad, publicaremos esos cambios en esta p\u00e1gina.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<\/p><hr style=\"box-sizing: content-box; margin-top: 20px; margin-bottom: 20px; border-top-color: #eeeeee; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<h1 style=\"overflow-wrap: break-word; margin: 15px 0px; font-size: 40px; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 45px; color: #033b4a; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\">&nbsp;<\/h1>\n<h1 style=\"overflow-wrap: break-word; margin: 15px 0px; font-size: 40px; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 45px; color: #033b4a; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>Formulario de Informaci\u00f3n sobre Obtenci\u00f3n y Tratamiento de Datos Personales&nbsp;<\/span><\/h1>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<\/p><p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><b><a href=\"https:\/\/www.dr-mfo.com\/es\/who-is-drmfo\/\">Dr. OFM<\/a> \u2013 Arte, Cirug\u00eda y Belleza<\/b>&nbsp;puede actuar como &quot;Supervisor de datos&quot; en virtud de la Ley de Protecci\u00f3n de Datos Personales no. 6698 (la \u201cLey\u201d) y dem\u00e1s leyes y reglamentos pertinentes procesan sus datos personales en el marco siguiente y en estricto cumplimiento de la Ley de Servicios B\u00e1sicos de Salud n\u00fam. 3359, el Decreto Gubernativo-Ley de Organizaci\u00f3n y Funciones del Ministerio de Salud y sus Empresas Afiliadas no. 663, Reglamento de Hospitales Privados, y dem\u00e1s normas del Ministerio de Salud, y dem\u00e1s leyes y disposiciones aplicables.<\/p>\n<h2 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 35px; color: #033b4a; margin: 15px 0px; font-size: 30px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>1. Obtenci\u00f3n y Tratamiento de Datos Personales, y Fines del Tratamiento:<\/span><\/h2>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>A. A qui\u00e9n puede interesar&nbsp;<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Como supervisor de datos, Dr. MFO \u2013 Art, Surgery &amp; Beauty recopila datos personales para los siguientes temas:&nbsp;<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li aria-level=\"1\">nuestros trabajadores<\/li>\n<li aria-level=\"1\">Nuestros Candidatos Trabajadores (incluidas las personas de referencia declaradas por los solicitantes de empleo)<\/li>\n<li aria-level=\"1\">Nuestros pasantes y aprendices en el trabajo,<\/li>\n<li aria-level=\"1\">Nuestros pacientes,<\/li>\n<li aria-level=\"1\">Personas entrevistadas y contactadas para diagn\u00f3stico, tratamiento o para recibir tales servicios,<\/li>\n<li aria-level=\"1\">Familiares y acompa\u00f1antes de pacientes,<\/li>\n<li aria-level=\"1\">Las partes de cualquier actividad comercial o las personas o empleados de las empresas con las que cooperamos o cooperaremos debido a actividades comerciales (suministro, publicidad, soporte, marketing, alojamiento, transporte, recursos de referencia, etc.)<\/li>\n<li aria-level=\"1\">Accionistas o personas con quienes se celebren negociaciones accionarias,<\/li>\n<li aria-level=\"1\">Nuestros Asesores Legales, Abogados y Consultores o autorizados o empleados de empresas consultoras,<\/li>\n<li aria-level=\"1\">visitantes<\/li>\n<li aria-level=\"1\">Representantes legales, padres, tutores o tutores de todos los interesados<\/li>\n<li aria-level=\"1\">Personas que son partes en procesos judiciales y sus representantes legales<\/li>\n<li aria-level=\"1\">Terceros con los que hayamos contactado, aunque no tengan vinculaci\u00f3n comercial o jur\u00eddica con nuestra empresa.<\/li>\n<\/ul>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>B. Datos tratados por&nbsp;<\/span>Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza<\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Sus datos personales se recopilan y obtienen verbalmente, por escrito, o en medios visuales o electr\u00f3nicos, a trav\u00e9s de un centro de llamadas, sitio de Internet, verbalmente, por escrito u otros canales similares para la realizaci\u00f3n de servicios tales como protecci\u00f3n de la salud p\u00fablica, medicina preventiva, diagn\u00f3stico m\u00e9dico. , tratamiento y servicios de mantenimiento ofrecidos por Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza, o para la planificaci\u00f3n y gesti\u00f3n de servicios de salud y financiaci\u00f3n, y de acuerdo con las \u00e1reas de negocio de Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza. Sus datos personales generales y datos personales especiales, especialmente sus datos de atenci\u00f3n m\u00e9dica, pueden ser procesados por el Grupo en una medida limitada para todos y cualquier prop\u00f3sito, incluidos, entre otros, los siguientes prop\u00f3sitos:<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li aria-level=\"1\">Sus datos e informaci\u00f3n de identidad: Su nombre, apellido, N\u00famero TC o n\u00famero de identidad TR temporal, n\u00famero de pasaporte, fecha y lugar de nacimiento, estado civil, sexo, n\u00famero de seguro social o de protocolo del paciente, as\u00ed como otros datos de identidad que puedan ser de utilidad en la identificaci\u00f3n de usted por nosotros,<\/li>\n<li aria-level=\"1\">Su informaci\u00f3n de comunicaci\u00f3n: Su direcci\u00f3n, n\u00famero de tel\u00e9fono, direcci\u00f3n de correo electr\u00f3nico y otros datos de comunicaci\u00f3n, y su entrevista verbal o registros de llamadas mantenidos por los departamentos de atenci\u00f3n al cliente o atenci\u00f3n al paciente seg\u00fan los est\u00e1ndares del centro de llamadas, as\u00ed como sus datos personales recopilados cuando usted comunicarse con nosotros por correo electr\u00f3nico, carta u otros medios de comunicaci\u00f3n,<\/li>\n<li aria-level=\"1\">Su informaci\u00f3n contable: su n\u00famero de cuenta bancaria, n\u00famero IBAN, datos de la tarjeta de cr\u00e9dito, datos de facturaci\u00f3n y otros datos e informaci\u00f3n financieros similares,<\/li>\n<li aria-level=\"1\">Los datos de su seguro m\u00e9dico privado y los datos e informaci\u00f3n de la Agencia de Seguridad Social seg\u00fan sea necesario para financiar y planificar los servicios de atenci\u00f3n m\u00e9dica,<\/li>\n<li aria-level=\"1\">Las grabaciones de su c\u00e1mara y las im\u00e1genes tomadas y guardadas con fines de seguridad y auditor\u00eda siempre y cuando visite nuestros hospitales o centros m\u00e9dicos, incluidas im\u00e1genes, videos y textos de voz compartidos en l\u00ednea con fines de preconsulta y diagn\u00f3stico,&nbsp;<\/li>\n<li aria-level=\"1\">El n\u00famero de placa de su autom\u00f3vil si usa el \u00e1rea de estacionamiento de autom\u00f3viles,<\/li>\n<li aria-level=\"1\">Su informaci\u00f3n de atenci\u00f3n m\u00e9dica: sus datos personales sobre su salud y vida sexual adquiridos y recopilados durante la prestaci\u00f3n o como resultado de los servicios de diagn\u00f3stico, tratamiento y atenci\u00f3n m\u00e9dica, incluidos, entre otros, los resultados de sus an\u00e1lisis de laboratorio, resultados de pruebas, datos de ex\u00e1menes m\u00e9dicos, datos e informaci\u00f3n de citas, datos de control y datos e informaci\u00f3n de recetas,<\/li>\n<li aria-level=\"1\">Su informaci\u00f3n de atenci\u00f3n m\u00e9dica y otros datos personales enviados o insertados por usted en el sitio www.dr-mfo.com, o en la direcci\u00f3n https:\/\/www.dr-mfo.com\/get-deatiled-information\/,<\/li>\n<li aria-level=\"1\">Si y cuando presenta una solicitud de empleo a Dr. MFO - Arte, Cirug\u00eda y Belleza o a cualquiera de las plataformas de Dr. MFO - Arte, Cirug\u00eda y Belleza, sus datos e informaci\u00f3n personal, incluido su curr\u00edculum vitae, enviado por usted, y si es empleado o empleado relacionado de Dr. MFO \u2013 Art, Surgery &amp; Beauty, su contrato de trabajo y toda clase de sus datos personales sobre su predisposici\u00f3n laboral.<\/li>\n<\/ul>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>C. Prop\u00f3sitos para procesar los datos por&nbsp;<\/span>Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza<\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Todos los tipos de sus datos personales obtenidos por Dr. MFO \u2013 Art, Surgery &amp; Beauty (incluidos, entre otros, sus datos personales especiales) pueden ser procesados por los siguientes motivos:<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li aria-level=\"1\">A la confirmaci\u00f3n de su identidad,<\/li>\n<li aria-level=\"1\">A la protecci\u00f3n de la salud p\u00fablica, la medicina preventiva, el diagn\u00f3stico m\u00e9dico, los servicios de tratamiento y mantenimiento, y para la planificaci\u00f3n y gesti\u00f3n de los servicios de salud y su financiaci\u00f3n,&nbsp;<\/li>\n<li aria-level=\"1\">Compartir la informaci\u00f3n solicitada con el Ministerio de Salud y otras entidades y administraciones p\u00fablicas relevantes de conformidad con las leyes y reglamentos aplicables,<\/li>\n<li aria-level=\"1\">Planificaci\u00f3n y gesti\u00f3n de las operaciones internas y operaciones diarias de nuestros Hospitales y Centros M\u00e9dicos,<\/li>\n<li aria-level=\"1\">Medici\u00f3n, mejora y estudio de la satisfacci\u00f3n del paciente por parte de los departamentos de Gesti\u00f3n Hospitalaria, Derechos del Paciente y Experiencia del Paciente,<\/li>\n<li aria-level=\"1\">Adquisici\u00f3n de medicamentos,<\/li>\n<li aria-level=\"1\">Si obtiene una cita, mantenerlo informado sobre la cita<\/li>\n<li aria-level=\"1\">Realizaci\u00f3n de actividades de gesti\u00f3n de riesgos y mejora de la calidad,<\/li>\n<li aria-level=\"1\">Realizaci\u00f3n de an\u00e1lisis para un mayor desarrollo de los servicios de salud,&nbsp;<\/li>\n<li aria-level=\"1\">Financiamiento de sus servicios de atenci\u00f3n m\u00e9dica por parte de los departamentos de Servicios al paciente, Asuntos financieros y Mercadotecnia, y el pago de los costos de su examen m\u00e9dico, diagn\u00f3stico y tratamiento, y el intercambio de la informaci\u00f3n solicitada con compa\u00f1\u00edas de seguros de salud privadas como parte de su consulta de elegibilidad.<\/li>\n<li aria-level=\"1\">Realizaci\u00f3n de investigaciones y estudios,<\/li>\n<li aria-level=\"1\">Cumplimiento de los requisitos y condiciones legales y reglamentarios,&nbsp;<\/li>\n<li aria-level=\"1\">Compartir la informaci\u00f3n solicitada con empresas privadas de seguros de salud en el curso de la financiaci\u00f3n de los servicios de atenci\u00f3n m\u00e9dica, y<\/li>\n<li aria-level=\"1\">Realizaci\u00f3n de actividades de gesti\u00f3n de riesgos y desarrollo de calidad por parte de los departamentos de Calidad, Experiencia del paciente y Sistemas de informaci\u00f3n,&nbsp;<\/li>\n<li aria-level=\"1\">Emisi\u00f3n de facturas por Servicios al Paciente, Asuntos Financieros y departamentos respectivos en consideraci\u00f3n de nuestros servicios, y confirmaci\u00f3n de sus relaciones con las instituciones y firmas contratadas, y<\/li>\n<li aria-level=\"1\">Participaci\u00f3n en campa\u00f1as y divulgaci\u00f3n de informaci\u00f3n de campa\u00f1as, y dise\u00f1o y transmisi\u00f3n de contenidos especiales, prestaciones discretas y abstractas en canales web y m\u00f3vil, por parte de los departamentos de Medios y Comunicaci\u00f3n, y Call Center.<\/li>\n<\/ul>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Sus datos personales obtenidos y procesados conforme a las leyes y reglamentos aplicables podr\u00e1n ser transferidos a archivos f\u00edsicos y\/o sistemas de informaci\u00f3n de Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza y podr\u00e1n ser conservados y almacenados tanto en plataformas digitales como f\u00edsicas.<\/p>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>D. OBTENCI\u00d3N DE DATOS PERSONALES<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Sus datos personales se obtienen y procesan a trav\u00e9s de m\u00faltiples canales y fuentes, que incluyen:&nbsp;<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li aria-level=\"1\">Resultado de la reuni\u00f3n con nuestro call center,<\/li>\n<li aria-level=\"1\">Resultado de la conversaci\u00f3n realizada sobre la aplicaci\u00f3n de soporte en vivo en nuestro sitio web,<\/li>\n<li aria-level=\"1\">El resultado de la entrevista se debe realizar contactando al Dr. MFO \u2013 m\u00e9dico de Arte, Cirug\u00eda y Belleza o personal relacionado por tel\u00e9fono, aplicaci\u00f3n de WhatsApp o correo electr\u00f3nico,<\/li>\n<li aria-level=\"1\">A trav\u00e9s de los tel\u00e9fonos utilizados por el personal de marketing y promoci\u00f3n de Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza, o a trav\u00e9s de SMS o WhatsApp, etc. Como resultado de la comunicaci\u00f3n establecida a trav\u00e9s de las aplicaciones,<\/li>\n<li aria-level=\"1\">Si aplica al Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza, puede comunicarse con el m\u00e9dico o personal relacionado por tel\u00e9fono, SMS o WhatsApp, etc. Como resultado de las entrevistas, realizar\u00e1 las solicitudes,<\/li>\n<li aria-level=\"1\">Si aplica a Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza, como resultado de reuniones cara a cara con m\u00e9dicos o personal relacionado,<\/li>\n<li aria-level=\"1\">Datos personales de las personas y funcionarios o empleados de la empresa con quienes se establece la relaci\u00f3n comercial como requisito de la actividad comercial, en el contrato y dem\u00e1s documentos de la actividad comercial, en las plataformas de comunicaci\u00f3n,<\/li>\n<li aria-level=\"1\">Como consecuencia de la inclusi\u00f3n de datos personales en el contrato y otros documentos de la actividad comercial de nuestros Asesores Legales, Abogados y Consultores o personas autorizadas o empleados de empresas consultoras, en plataformas de comunicaci\u00f3n,<\/li>\n<li aria-level=\"1\">Como resultado de las solicitudes realizadas a trav\u00e9s de paneles como \u201ccont\u00e1ctanos\u201d o \u201cinf\u00f3rmate\u201d mediante la promoci\u00f3n y publicidad en redes sociales,<\/li>\n<li aria-level=\"1\">Como consecuencia de la solicitud de un n\u00famero de tel\u00e9fono m\u00f3vil para datos personales y el cifrado solicitado de acuerdo con la legislaci\u00f3n para poder conectarse a la transmisi\u00f3n en la red inal\u00e1mbrica (Wi-Fi) espec\u00edfica de los hu\u00e9spedes en el \u00e1mbito de Internet inal\u00e1mbrico servicio,<\/li>\n<li aria-level=\"1\">Obtener datos en forma de registro de MAC ID (Informaci\u00f3n de identidad del dispositivo) de los inicios de sesi\u00f3n en el sitio web,<\/li>\n<li aria-level=\"1\">Si estamos en contacto con Dr. MFO \u2013 Art, Surgery &amp; Beauty o si nos contactan sin una conexi\u00f3n comercial o legal, los datos personales de terceros se incluyen en las plataformas de comunicaci\u00f3n,<\/li>\n<li aria-level=\"1\">Del mismo modo, con otros m\u00e9todos legales de adquisici\u00f3n de datos,<\/li>\n<li aria-level=\"1\">Se obtiene de dichos canales.<\/li>\n<\/ul>\n<h2 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 35px; color: #033b4a; margin: 15px 0px; font-size: 30px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>2. Transferencia de Datos Personales<\/span><\/h2>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Sus datos personales pueden ser compartidos por el Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza con los departamentos internos de restauraci\u00f3n y archivo de datos o con terceros externos, incluidos:<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li aria-level=\"1\">Ministerio de Salud, subunidades y centros de medicina familiar adscritos al ministerio,<\/li>\n<li aria-level=\"1\">Compa\u00f1\u00edas de seguros privados (seguros de salud, pensiones, vida, etc.),<\/li>\n<li aria-level=\"1\">instituci\u00f3n de seguridad social,<\/li>\n<li aria-level=\"1\">Ministerio de Familia, Trabajo y Pol\u00edticas Sociales,<\/li>\n<li aria-level=\"1\">Direcci\u00f3n General de Seguridad y otros organismos encargados de hacer cumplir la ley,<\/li>\n<li aria-level=\"1\">Direcci\u00f3n General de Asuntos de Poblaci\u00f3n y Ciudadan\u00eda,<\/li>\n<li aria-level=\"1\">Otras instituciones y organismos oficiales autorizados,<\/li>\n<li aria-level=\"1\">asociaci\u00f3n de farmac\u00e9uticos turcos,<\/li>\n<li aria-level=\"1\">Autoridades judiciales, oficinas de ejecuci\u00f3n, mediadores,<\/li>\n<li aria-level=\"1\">Laboratorios, centros m\u00e9dicos, ambulancias, dispositivos m\u00e9dicos e instituciones prestadoras de servicios de salud en el pa\u00eds o en el extranjero con los que cooperamos para el diagn\u00f3stico y tratamiento m\u00e9dico,<\/li>\n<li aria-level=\"1\">La instituci\u00f3n de salud a la que fue derivado el paciente o a la que el propio paciente aplic\u00f3,<\/li>\n<li aria-level=\"1\">Representantes legales, padres y tutores autorizados por escrito<\/li>\n<li aria-level=\"1\">Terceros, naturales o jur\u00eddicos, de quienes se reciben servicios de consultor\u00eda, incluidos abogados, asesores fiscales y auditores con los que trabajamos en virtud del contrato,<\/li>\n<li aria-level=\"1\">Instituciones reguladoras y supervisoras y autoridades oficiales,<\/li>\n<li aria-level=\"1\">Empresas dentro del grupo de empresas a las que est\u00e1 afiliado nuestro Hospital,<\/li>\n<li aria-level=\"1\">Bancos donde nuestra empresa o los pacientes o nuestros empleados que est\u00e1n relacionados con nuestra empresa de conformidad con cualquier contrato tienen cuentas,<\/li>\n<li aria-level=\"1\">Empresas privadas de pensiones que operen en el \u00e1mbito del IPS (Sistema Individual de Pensiones) obligatorio o voluntario,<\/li>\n<li aria-level=\"1\">Nuestros proveedores, proveedores de servicios de soporte, proveedores de servicios de archivo y socios comerciales de cuyos servicios nos beneficiamos o con los que cooperamos (para obtener informaci\u00f3n m\u00e1s detallada, puede obtener informaci\u00f3n solicitando a nuestro hospital por escrito).<\/li>\n<li aria-level=\"1\">A nuestros socios comerciales y contactos comerciales,<\/li>\n<li aria-level=\"1\">A nuestros accionistas y personas f\u00edsicas o jur\u00eddicas con quienes se hayan realizado entrevistas de accionistas.<\/li>\n<li aria-level=\"1\">proveedores de servicios de externalizaci\u00f3n,<\/li>\n<li aria-level=\"1\">Empresas de carga o mensajer\u00eda,<\/li>\n<li aria-level=\"1\">Empresas de transporte a\u00e9reo, terrestre o mar\u00edtimo de pasajeros,<\/li>\n<\/ul>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Para los fines del tratamiento antes se\u00f1alados, de conformidad con la Ley y dem\u00e1s disposiciones legales y reglamentarias aplicables.<\/p>\n<h2 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 35px; color: #033b4a; margin: 15px 0px; font-size: 30px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>3. Modalidades y Causas Legales de Obtenci\u00f3n de Datos Personales<\/span><\/h2>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Sus datos personales son recabados y tratados en toda clase de medios verbales, escritos, visuales o electr\u00f3nicos, con las finalidades antes enumeradas, y para la realizaci\u00f3n de toda clase de trabajos comprendidos en el \u00e1mbito de actuaci\u00f3n de Dr. MFO \u2013 Arte, Cirug\u00eda &amp; Belleza dentro del marco legal, y en consecuencia, para el pleno y debido cumplimiento de todo tipo de deberes y obligaciones contractuales y legales del Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza. Las causas legales de recolecci\u00f3n y adquisici\u00f3n de sus datos personales son las disposiciones pertinentes de:<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li aria-level=\"1\">Servicios de Salud Ley B\u00e1sica N\u00b0 3359,<\/li>\n<li aria-level=\"1\">Decreto-Ley N\u00b0 663 sobre Organizaci\u00f3n y Funciones del Ministerio de Salud y sus Dependientes,<\/li>\n<li aria-level=\"1\">Ley N\u00b0 6698 de Protecci\u00f3n de Datos Personales,<\/li>\n<li aria-level=\"1\">Reglamento de Hospitales Privados,<\/li>\n<li aria-level=\"1\">Reglamento sobre Tratamiento de Datos Personales de Salud y Protecci\u00f3n de la Privacidad<\/li>\n<li aria-level=\"1\">Ley de Notificaci\u00f3n de Identidad N\u00b0 1774,<\/li>\n<li aria-level=\"1\">Ley del Trabajo N\u00b0 4857,<\/li>\n<li aria-level=\"1\">Ley del Seguro Social y Seguro General de Salud N\u00b0 5510,<\/li>\n<\/ul>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Asimismo, la Protecci\u00f3n de Datos Personales N\u00b0 6698, seg\u00fan establece el numeral 3 del art\u00edculo 6 de la Ley, los datos personales relacionados con la salud y la vida sexual s\u00f3lo podr\u00e1n ser utilizados para la protecci\u00f3n de la salud p\u00fablica, medicina preventiva, diagn\u00f3stico m\u00e9dico, tratamiento y servicios de atenci\u00f3n, planificaci\u00f3n y gesti\u00f3n de servicios de salud y financiamiento. Puede ser tratado por personas o instituciones y organismos autorizados bajo la obligaci\u00f3n de guardar secreto sin recabar el consentimiento expl\u00edcito del interesado.<\/p>\n<h2 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 35px; color: #033b4a; margin: 15px 0px; font-size: 30px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>4. Nuestras Medidas y Compromisos en Materia de Protecci\u00f3n de Datos Personales&nbsp;<\/span><\/h2>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><span style=\"background-color: rgb(249, 249, 254); color: rgb(102, 102, 102); font-family: &quot;Open Sans&quot;; font-size: 16px;\">Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza<\/span>, como responsable del tratamiento, protege los datos personales y privados antes mencionados en sus propios entornos f\u00edsicos y electr\u00f3nicos con alta sensibilidad y dando pleno cumplimiento a lo dispuesto en la legislaci\u00f3n, tomando todo tipo de medidas administrativas y t\u00e9cnicas.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><span style=\"background-color: rgb(249, 249, 254); color: rgb(102, 102, 102); font-family: &quot;Open Sans&quot;; font-size: 16px;\">Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza&nbsp;<\/span>ha adoptado todo tipo de medidas administrativas y t\u00e9cnicas para proteger sus datos personales, registrados en VERBIS e incluidos en el Inventario de Datos Personales.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><span style=\"background-color: rgb(249, 249, 254); color: rgb(102, 102, 102); font-family: &quot;Open Sans&quot;; font-size: 16px;\">Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza&nbsp;<\/span>se compromete a proteger todos los datos personales. Para evitar el procesamiento y acceso ilegal de datos personales y garantizar la protecci\u00f3n de los datos personales, se llevan a cabo medidas t\u00e9cnicas y administrativas para garantizar el nivel adecuado de seguridad mediante el uso de diversos m\u00e9todos y tecnolog\u00edas de seguridad.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><span style=\"background-color: rgb(249, 249, 254); color: rgb(102, 102, 102); font-family: &quot;Open Sans&quot;; font-size: 16px;\">Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza&nbsp;<\/span>no divulgar\u00e1 a terceros los datos personales que haya obtenido en contravenci\u00f3n a lo dispuesto en la Ley de Protecci\u00f3n de Datos Personales N\u00b0 6698 y no los utilizar\u00e1 para fines distintos al tratamiento.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><span style=\"background-color: rgb(249, 249, 254); color: rgb(102, 102, 102); font-family: &quot;Open Sans&quot;; font-size: 16px;\">Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza&nbsp;<\/span>ha preparado y firmado todas las advertencias o declaraciones de consentimiento, compromisos e implementado las actividades de auditor\u00eda multifac\u00e9ticas necesarias para los casos en los que es necesario y necesario compartir (transferir) datos personales con proveedores de servicios subcontratados y proveedores, consultores o abogados.<\/p>\n<h2 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 35px; color: #033b4a; margin: 15px 0px; font-size: 30px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>5. Seguridad de los datos<\/span><\/h2>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><span style=\"background-color: rgb(249, 249, 254); color: rgb(102, 102, 102); font-family: &quot;Open Sans&quot;; font-size: 16px;\">Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza&nbsp;<\/span>protege sus datos personales en total y estricto cumplimiento de todos los controles de seguridad t\u00e9cnicos y administrativos que se requieren de conformidad con las normas y procedimientos de seguridad de la informaci\u00f3n. Las acciones y medidas de seguridad se toman y proporcionan a un nivel apropiado para los riesgos probables teniendo tambi\u00e9n en cuenta las posibilidades tecnol\u00f3gicas.<\/p>\n<h4 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 25px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 20px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>TRATAMIENTO DE DATOS PERSONALES RECOGIDOS MEDIANTE COOKIES<\/span><\/h4>\n<h4 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 25px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 20px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span><span style=\"font-weight: 400;\">Dr. MFO \u2013 Art, Surgery &amp; Beauty no coloca cookies en su sitio web. Durante el uso de nuestro sitio web y aplicaci\u00f3n m\u00f3vil, direcci\u00f3n IP, informaci\u00f3n del navegador. (ID de Mac, informaci\u00f3n de direcci\u00f3n IP, inicio de sesi\u00f3n del sitio web e informaci\u00f3n de contrase\u00f1a) no se reciben.<\/span><\/span><\/h4>\n<h2 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 35px; color: #033b4a; margin: 15px 0px; font-size: 30px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>6. Sus derechos en materia de protecci\u00f3n de datos personales<\/span><\/h2>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>A. Sus derechos en materia de protecci\u00f3n de datos personales<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">De conformidad con el art\u00edculo 11 de la Ley de Protecci\u00f3n de Datos Personales, usted puede ejercer sus derechos respecto del tratamiento y protecci\u00f3n de sus datos personales, siempre que acredite su identidad solicitando a Dr. MFO \u2013 Art, Surgery &amp; Beauty como Responsable del Tratamiento a trav\u00e9s del siguientes caminos<\/p>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li aria-level=\"1\">Saber si sus datos personales son tratados o no,<\/li>\n<li aria-level=\"1\">Si sus datos personales han sido tratados, solicitando informaci\u00f3n al respecto,<\/li>\n<li aria-level=\"1\">Conocer la finalidad del tratamiento de sus datos personales y si se utilizan de acuerdo con la finalidad,<\/li>\n<li aria-level=\"1\">Conocer los terceros a quienes se transfieren sus datos personales, nacionales o extranjeros,<\/li>\n<li aria-level=\"1\">Solicitar la correcci\u00f3n de datos personales si est\u00e1n incompletos o procesados incorrectamente<\/li>\n<li aria-level=\"1\">Solicitar la eliminaci\u00f3n o destrucci\u00f3n de datos personales,<\/li>\n<li aria-level=\"1\">En caso de que sus datos personales hayan sido transferidos a terceros, solicitando que sus datos personales sean corregidos y eliminados o destruidos, en caso de que sus datos personales est\u00e9n incompletos o procesados incorrectamente, para ser notificados o enviados al tercero correspondiente,<\/li>\n<li aria-level=\"1\">Oponerse a la aparici\u00f3n de un resultado en contra de la persona misma mediante el an\u00e1lisis de los datos procesados exclusivamente a trav\u00e9s de sistemas automatizados,<\/li>\n<li aria-level=\"1\">Solicitar la eliminaci\u00f3n del da\u00f1o en caso de da\u00f1o debido al tratamiento il\u00edcito de datos personales,<\/li>\n<li aria-level=\"1\">tienes los derechos<\/li>\n<li aria-level=\"1\">Puede solicitar la destrucci\u00f3n (supresi\u00f3n, destrucci\u00f3n o anonimizaci\u00f3n) de sus datos personales a Dr. MFO \u2013 Art, Surgery &amp; Beauty en el marco de las condiciones previstas en el art\u00edculo 7 de la Ley de Protecci\u00f3n de Datos Personales. Sin embargo, al evaluar su solicitud de destrucci\u00f3n, nuestra empresa evaluar\u00e1 qu\u00e9 m\u00e9todo es el adecuado de acuerdo con las condiciones del caso concreto. En este contexto, siempre puede solicitar informaci\u00f3n al Dr. MFO \u2013 Art, Surgery &amp; Beauty sobre por qu\u00e9 hemos elegido el m\u00e9todo de destrucci\u00f3n que hemos elegido.<\/li>\n<li aria-level=\"1\">Los datos personales recopilados sobre personas menores de 18 a\u00f1os se limitan a su nombre, apellido, edad y grado de afinidad, y estos datos solo nos los puede proporcionar el adulto correspondiente (padre o tutor).<\/li>\n<\/ul>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>B. Situaci\u00f3n fuera del \u00e1mbito de aplicaci\u00f3n&nbsp;<\/span><\/h3>\n<ul style=\"overflow-wrap: break-word; margin: 16px 0px; padding: 0px 0px 0px 25px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">\n<li aria-level=\"1\">De conformidad con el art\u00edculo 28 de la Ley de Protecci\u00f3n de Datos Personales, los titulares de datos personales no podr\u00e1n hacer valer su derecho de solicitud, ya que quedan excluidos del \u00e1mbito de aplicaci\u00f3n de la Ley KVK los siguientes casos:<\/li>\n<li aria-level=\"1\">Procesar datos personales para fines tales como investigaci\u00f3n, planificaci\u00f3n y estad\u00edsticas al anonimizarlos con estad\u00edsticas oficiales.<\/li>\n<li aria-level=\"1\">Tratamiento de datos personales con fines art\u00edsticos, hist\u00f3ricos, literarios o cient\u00edficos o en el \u00e1mbito de la libertad de expresi\u00f3n, siempre que no vulnere la defensa nacional, la seguridad nacional, la seguridad p\u00fablica, el orden p\u00fablico, la seguridad econ\u00f3mica, la intimidad de la vida privada o los derechos personales o no constituye un delito.<\/li>\n<li aria-level=\"1\">Tratamiento de datos personales en el marco de actividades preventivas, de protecci\u00f3n y de inteligencia realizadas por instituciones y organismos p\u00fablicos autorizados por la ley para garantizar la defensa nacional, la seguridad nacional, la seguridad p\u00fablica, el orden p\u00fablico o la seguridad econ\u00f3mica.<\/li>\n<li aria-level=\"1\">Tratamiento de datos personales por autoridades judiciales o autoridades de ejecuci\u00f3n en relaci\u00f3n con procedimientos de investigaci\u00f3n, enjuiciamiento, juicio o ejecuci\u00f3n.<\/li>\n<li aria-level=\"1\">De conformidad con el numeral 2 del art\u00edculo 28 de la Ley de Protecci\u00f3n de Datos Personales, no es posible hacer valer derechos en los siguientes casos, con excepci\u00f3n del derecho a exigir la reparaci\u00f3n del da\u00f1o:<\/li>\n<li aria-level=\"1\">El procesamiento de datos personales es necesario para la prevenci\u00f3n de delitos o para la investigaci\u00f3n criminal,<\/li>\n<li aria-level=\"1\">Tratamiento de datos personales hechos p\u00fablicos por el interesado,<\/li>\n<li aria-level=\"1\">El procesamiento de datos personales es necesario para la ejecuci\u00f3n de funciones de supervisi\u00f3n o regulaci\u00f3n y para la investigaci\u00f3n disciplinaria o el enjuiciamiento por parte de instituciones y organizaciones p\u00fablicas autorizadas y autorizadas y organizaciones profesionales con car\u00e1cter de instituci\u00f3n p\u00fablica, con base en la autoridad otorgada por la ley,<\/li>\n<li aria-level=\"1\">El tratamiento de datos personales es necesario para la protecci\u00f3n de los intereses econ\u00f3micos y financieros del Estado en materia presupuestaria, fiscal y financiera.<\/li>\n<\/ul>\n<h3 style=\"overflow-wrap: break-word; font-family: Saira, Arial, Helvetica, sans-serif; font-weight: 600; line-height: 30px; color: #033b4a; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; font-size: 25px; clear: both; text-rendering: optimizelegibility; background-color: #ffffff;\"><span>C. SUS FORMAS DE CONTACTAR A NUESTRA EMPRESA PARA UTILIZAR SUS DERECHOS<\/span><\/h3>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Sus derechos est\u00e1n protegidos por la Ley de Protecci\u00f3n de Datos Personales;<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">1- Al completar el formulario de solicitud en el sitio web de nuestra empresa &quot;https:\/\/www.dr-mfo.com\/get-detailed-information\/&quot;, p\u00e1gina de contacto&nbsp;<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">2- Rellenando el formulario de solicitud en persona en K\u0131\u015fla Saray mh Harbiye blv 22\/2 Antakya\/T\u00dcRK\u0130YE, donde se encuentra la sede de nuestra empresa, obtenido del departamento de Gesti\u00f3n de Recursos Humanos&nbsp;<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">3- Mediante el env\u00edo de una carta a trav\u00e9s de un notario p\u00fablico,<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">4- Mediante el env\u00edo de un correo electr\u00f3nico a la direcci\u00f3n de correo electr\u00f3nico registrada con firma electr\u00f3nica o m\u00f3vil segura a la direcci\u00f3n de correo mfo@dr-mfo.com,<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><em><span style=\"font-weight: bold;\">Aviso<\/span><\/em><\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Dependiendo de la naturaleza de su solicitud y su m\u00e9todo de solicitud, la Compa\u00f1\u00eda puede solicitar verificaciones adicionales (como enviar un mensaje a su tel\u00e9fono registrado, llamar) para determinar si la solicitud le pertenece o no, y as\u00ed proteger sus derechos. . Por ejemplo, si presenta su solicitud a trav\u00e9s de su direcci\u00f3n de correo electr\u00f3nico registrada con la Compa\u00f1\u00eda, es posible que lo contactemos utilizando otro m\u00e9todo de comunicaci\u00f3n registrado con la Compa\u00f1\u00eda y se le puede pedir que confirme si la solicitud le pertenece.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Como regla general, sus solicitudes en su solicitud se concluir\u00e1n sin cargo dentro de los treinta d\u00edas h\u00e1biles a m\u00e1s tardar, seg\u00fan la naturaleza de la solicitud. Sin embargo, si la transacci\u00f3n requiere un costo aparte para la Empresa, seg\u00fan se establece en el Comunicado sobre Procedimientos y Principios de Aplicaci\u00f3n al Responsable del Tratamiento publicado en el Diario Oficial del 03.10.2018 y n\u00famero 30356 de la Autoridad de Protecci\u00f3n de Datos Personales, un total de 50 (Cincuenta) TL no se puede exceder. Una cuota puede ser cargada. Si su solicitud se debe a una falla de nuestra empresa, que es el controlador de datos, se le reembolsar\u00e1 la tarifa pagada.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Sus debidas solicitudes de Protecci\u00f3n de Datos Personales, por lo general, ser\u00e1n concluidas en forma gratuita, a m\u00e1s tardar dentro de los treinta d\u00edas h\u00e1biles, contados a partir de su recepci\u00f3n en nuestra empresa.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Para confirmar que usted es la persona adecuada en el caso de su solicitud, \u201cDr. MFO \u2013 Arte, Cirug\u00eda y Belleza\u201d tiene derecho a solicitarle cierta informaci\u00f3n de confirmaci\u00f3n. A menos que cancele su solicitud, se considera que ha aceptado estas solicitudes del Dr. MFO - Arte, Cirug\u00eda y Belleza.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><em><span style=\"font-weight: bold;\">CONSENTIMIENTO y APROBACI\u00d3N<\/span><\/em><\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Al leer este Texto Aclaratorio, acepta, declara y se compromete a estar plena y completamente informado sobre el hecho de que Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza.<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\"><em><span style=\"font-weight: bold;\">INFORMACI\u00d3N DEL CONTACTO<\/span><\/em><\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Dr. MFO \u2013 Arte, Cirug\u00eda y Belleza<br><\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Enlace de contacto: www.dr-mfo.com<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">E-Mail:&nbsp;mfo@dr-mfo.com<\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">DIRECCI\u00d3N:&nbsp;<span style=\"background-color: rgb(249, 249, 254); color: rgb(102, 102, 102); font-family: &quot;Open Sans&quot;; font-size: 16px;\">K\u0131\u015fla Saray mh Harbiye blv 22\/2 Antakya\/T\u00dcRK\u0130YE<\/span><\/p>\n<p style=\"overflow-wrap: break-word; margin-right: 0px; margin-bottom: 15px; margin-left: 0px; color: #54595d; font-family: Saira, Tahoma, Geneva, sans-serif; font-size: 15px; background-color: #ffffff;\">Tel\u00e9fono: +90 552 700 3322<\/p>\n<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy &amp; Cookie Policy We collect information from you when you register on our site or fill out a form.When ordering or registering on our site, as appropriate, you may be asked to enter your name, email address, phone number or other details to help you with your experience. What do we use your information [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4089","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dr-mfo.com\/es\/wp-json\/wp\/v2\/pages\/4089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dr-mfo.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dr-mfo.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dr-mfo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dr-mfo.com\/es\/wp-json\/wp\/v2\/comments?post=4089"}],"version-history":[{"count":0,"href":"https:\/\/www.dr-mfo.com\/es\/wp-json\/wp\/v2\/pages\/4089\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dr-mfo.com\/es\/wp-json\/wp\/v2\/media?parent=4089"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}